{"id":5,"count":35,"description":"","link":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/","name":"Blog","slug":"blog","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blog Archives - Franchise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog Archives - Franchise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"Franchise\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/category\\\/blog\\\/\",\"url\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/category\\\/blog\\\/\",\"name\":\"Blog Archives - Franchise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/category\\\/blog\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/category\\\/blog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/#website\",\"url\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/\",\"name\":\"Franchise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lightbridgeacademy.com\\\/franchise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog Archives - Franchise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/","og_locale":"en_US","og_type":"article","og_title":"Blog Archives - Franchise","og_url":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/","og_site_name":"Franchise","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/","url":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/","name":"Blog Archives - Franchise","isPartOf":{"@id":"https:\/\/lightbridgeacademy.com\/franchise\/#website"},"breadcrumb":{"@id":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lightbridgeacademy.com\/franchise\/category\/blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lightbridgeacademy.com\/franchise\/"},{"@type":"ListItem","position":2,"name":"Blog"}]},{"@type":"WebSite","@id":"https:\/\/lightbridgeacademy.com\/franchise\/#website","url":"https:\/\/lightbridgeacademy.com\/franchise\/","name":"Franchise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lightbridgeacademy.com\/franchise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/lightbridgeacademy.com\/franchise\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightbridgeacademy.com\/franchise\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lightbridgeacademy.com\/franchise\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lightbridgeacademy.com\/franchise\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}