{"id":9,"date":"2026-06-10T23:04:37","date_gmt":"2026-06-10T23:04:37","guid":{"rendered":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/daycare-enrollment-form\/"},"modified":"2026-06-13T00:02:03","modified_gmt":"2026-06-13T00:02:03","slug":"enrollment","status":"publish","type":"page","link":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/","title":{"rendered":"Enrollment"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/flex-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enrollment - Bethlehem, PA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrollment - Bethlehem, PA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/\" \/>\n<meta property=\"og:site_name\" content=\"Bethlehem, PA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-13T00:02:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/enrollment\\\/\",\"url\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/enrollment\\\/\",\"name\":\"Enrollment - Bethlehem, PA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/#website\"},\"datePublished\":\"2026-06-10T23:04:37+00:00\",\"dateModified\":\"2026-06-13T00:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/enrollment\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/enrollment\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/enrollment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrollment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/#website\",\"url\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/\",\"name\":\"Bethlehem, PA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lightbridgeacademy.com\\\/bethlehem-pa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrollment - Bethlehem, PA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/","og_locale":"en_US","og_type":"article","og_title":"Enrollment - Bethlehem, PA","og_url":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/","og_site_name":"Bethlehem, PA","article_modified_time":"2026-06-13T00:02:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/","url":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/","name":"Enrollment - Bethlehem, PA","isPartOf":{"@id":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/#website"},"datePublished":"2026-06-10T23:04:37+00:00","dateModified":"2026-06-13T00:02:03+00:00","breadcrumb":{"@id":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/enrollment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/"},{"@type":"ListItem","position":2,"name":"Enrollment"}]},{"@type":"WebSite","@id":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/#website","url":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/","name":"Bethlehem, PA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":1,"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":177,"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/pages\/9\/revisions\/177"}],"wp:attachment":[{"href":"https:\/\/lightbridgeacademy.com\/bethlehem-pa\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}